{"id":309,"date":"2021-10-29T14:20:30","date_gmt":"2021-10-29T14:20:30","guid":{"rendered":"https:\/\/kasparzehnder.com\/de\/?page_id=309"},"modified":"2025-05-10T12:00:12","modified_gmt":"2025-05-10T11:00:12","slug":"kalender","status":"publish","type":"page","link":"https:\/\/kasparzehnder.com\/de\/kalender\/","title":{"rendered":"Kalender"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"309\" class=\"elementor elementor-309\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b619249 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b619249\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74cf165\" data-id=\"74cf165\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-413732a animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"413732a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Next events - Concerts<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f934006 animated-fast elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"f934006\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be6082e animated-fast elementor-invisible elementor-widget elementor-widget-shortcode\" data-id=\"be6082e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"mec-wrap mec-skin-list-container  \" id=\"mec_skin_255\">\r\n\r\n    \r\n        <div class=\"mec-skin-list-events-container\" id=\"mec_skin_events_255\">\r\n        Keine Veranstaltung gefunden!    <\/div>\r\n    \r\n    \r\n<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3b11471 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b11471\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-276c382\" data-id=\"276c382\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5183887 elementor-widget__width-auto elementor-hidden-mobile elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"5183887\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdadaf5 elementor-widget__width-auto animated-fast elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cdadaf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Konzertkalender<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13433d6 elementor-widget__width-auto elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"13433d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d96f6c animated-fast elementor-invisible elementor-widget elementor-widget-MEC\" data-id=\"9d96f6c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"next-month-events\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"MEC.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mec-wrap mec-skin-list-container  \" id=\"mec_skin_324\">\r\n\r\n    \r\n        <div class=\"mec-skin-list-events-container\" id=\"mec_skin_events_324\">\r\n        Keine Veranstaltung gefunden!    <\/div>\r\n    \r\n    \r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9811aa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e9811aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2cf15c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b2cf15c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Monats\u00fcbersicht<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8548d animated-fast elementor-invisible elementor-widget elementor-widget-MEC\" data-id=\"cc8548d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"MEC.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mec_skin_315\" class=\"mec-wrap    mec-full-calendar-wrap\">\r\n\r\n    <div class=\"mec-search-form mec-totalcal-box\">\r\n            <\/div>\r\n\r\n    <div id=\"mec_full_calendar_container_315\" class=\"mec-full-calendar-skin-container\">\r\n        <div id=\"mec_skin_315\" class=\"mec-wrap   \">\r\n\r\n    \r\n    <div class=\"mec-calendar \">\r\n        <div class=\"mec-calendar-topsec\">        <div class=\"mec-calendar-side mec-clear\">\r\n                        <div class=\"mec-skin-monthly-view-month-navigator-container\">\r\n                <div class=\"mec-month-navigator\" id=\"mec_month_navigator_315_202609\"><div class=\"mec-previous-month mec-load-month mec-previous-month\" data-mec-year=\"2026\" data-mec-month=\"08\"><a href=\"#\" class=\"mec-load-month-link\"><i class=\"mec-sl-angle-left\"><\/i> August<\/a><\/div><div class=\"mec-calendar-header\"><h2>September 2026<\/h2><\/div><div class=\"mec-next-month mec-load-month mec-next-month\" data-mec-year=\"2026\" data-mec-month=\"10\"><a href=\"#\" class=\"mec-load-month-link\">Oktober <i class=\"mec-sl-angle-right\"><\/i><\/a><\/div><\/div>\r\n            <\/div>\r\n            \r\n            <div class=\"mec-calendar-table\" id=\"mec_skin_events_315\">\r\n                <div class=\"mec-month-container mec-month-container-selected\" id=\"mec_monthly_view_month_315_202609\" data-month-id=\"202609\"><dl class=\"mec-calendar-table-head\"><dt class=\"mec-calendar-day-head\">MO<\/dt><dt class=\"mec-calendar-day-head\">DI<\/dt><dt class=\"mec-calendar-day-head\">MI<\/dt><dt class=\"mec-calendar-day-head\">DO<\/dt><dt class=\"mec-calendar-day-head\">FR<\/dt><dt class=\"mec-calendar-day-head\">SA<\/dt><dt class=\"mec-calendar-day-head\">SO<\/dt><\/dl><dl class=\"mec-calendar-row\">\r\n    <dt class=\"mec-table-nullday\">31<\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260901\" data-day=\"1\" data-month=\"202609\">1<\/dt><\/dt><dt class=\"mec-calendar-day  mec-selected-day\" data-mec-cell=\"20260902\" data-day=\"2\" data-month=\"202609\">2<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260903\" data-day=\"3\" data-month=\"202609\">3<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260904\" data-day=\"4\" data-month=\"202609\">4<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260905\" data-day=\"5\" data-month=\"202609\">5<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260906\" data-day=\"6\" data-month=\"202609\">6<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day \" data-mec-cell=\"20260907\" data-day=\"7\" data-month=\"202609\">7<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260908\" data-day=\"8\" data-month=\"202609\">8<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260909\" data-day=\"9\" data-month=\"202609\">9<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260910\" data-day=\"10\" data-month=\"202609\">10<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260911\" data-day=\"11\" data-month=\"202609\">11<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260912\" data-day=\"12\" data-month=\"202609\">12<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260913\" data-day=\"13\" data-month=\"202609\">13<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day \" data-mec-cell=\"20260914\" data-day=\"14\" data-month=\"202609\">14<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260915\" data-day=\"15\" data-month=\"202609\">15<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260916\" data-day=\"16\" data-month=\"202609\">16<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260917\" data-day=\"17\" data-month=\"202609\">17<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260918\" data-day=\"18\" data-month=\"202609\">18<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260919\" data-day=\"19\" data-month=\"202609\">19<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260920\" data-day=\"20\" data-month=\"202609\">20<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day \" data-mec-cell=\"20260921\" data-day=\"21\" data-month=\"202609\">21<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260922\" data-day=\"22\" data-month=\"202609\">22<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260923\" data-day=\"23\" data-month=\"202609\">23<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260924\" data-day=\"24\" data-month=\"202609\">24<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260925\" data-day=\"25\" data-month=\"202609\">25<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260926\" data-day=\"26\" data-month=\"202609\">26<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260927\" data-day=\"27\" data-month=\"202609\">27<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day \" data-mec-cell=\"20260928\" data-day=\"28\" data-month=\"202609\">28<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260929\" data-day=\"29\" data-month=\"202609\">29<\/dt><\/dt><dt class=\"mec-calendar-day \" data-mec-cell=\"20260930\" data-day=\"30\" data-month=\"202609\">30<\/dt><\/dt><dt class=\"mec-table-nullday\">1<\/dt><dt class=\"mec-table-nullday\">2<\/dt><dt class=\"mec-table-nullday\">3<\/dt><dt class=\"mec-table-nullday\">4<\/dt><\/dl>\r\n<\/div>\r\n            <\/div>\r\n\r\n                    <\/div>\r\n        <div class=\"mec-calendar-events-side mec-clear\"><div class=\"mec-month-side\" id=\"mec_month_side_315_202609\"><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260901\" data-mec-cell=\"20260901\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 1<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260902\" data-mec-cell=\"20260902\"  style=\"display: block;\"><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 2<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260903\" data-mec-cell=\"20260903\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 3<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260904\" data-mec-cell=\"20260904\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 4<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260905\" data-mec-cell=\"20260905\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 5<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260906\" data-mec-cell=\"20260906\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 6<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260907\" data-mec-cell=\"20260907\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 7<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260908\" data-mec-cell=\"20260908\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 8<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260909\" data-mec-cell=\"20260909\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 9<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260910\" data-mec-cell=\"20260910\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 10<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260911\" data-mec-cell=\"20260911\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 11<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260912\" data-mec-cell=\"20260912\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 12<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260913\" data-mec-cell=\"20260913\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 13<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260914\" data-mec-cell=\"20260914\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 14<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260915\" data-mec-cell=\"20260915\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 15<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260916\" data-mec-cell=\"20260916\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 16<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260917\" data-mec-cell=\"20260917\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 17<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260918\" data-mec-cell=\"20260918\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 18<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260919\" data-mec-cell=\"20260919\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 19<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260920\" data-mec-cell=\"20260920\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 20<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260921\" data-mec-cell=\"20260921\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 21<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260922\" data-mec-cell=\"20260922\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 22<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260923\" data-mec-cell=\"20260923\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 23<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260924\" data-mec-cell=\"20260924\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 24<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260925\" data-mec-cell=\"20260925\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 25<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260926\" data-mec-cell=\"20260926\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 26<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260927\" data-mec-cell=\"20260927\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 27<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260928\" data-mec-cell=\"20260928\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 28<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260929\" data-mec-cell=\"20260929\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 29<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-315-20260930\" data-mec-cell=\"20260930\" ><h6 class=\"mec-table-side-title\">Veranstaltungen am <span class=\"mec-color mec-table-side-day\"> 30<\/span> September<\/h6><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Keine Veranstaltungen<\/div><\/article><\/div><\/div><\/div><\/div><div class=\"mec-event-footer\"><\/div>    <\/div>\r\n\r\n<\/div>    <\/div>\r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-536cf80 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"536cf80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-adf68e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adf68e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98c0013\" data-id=\"98c0013\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629e5ca animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"629e5ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:&quot;100&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vergangene Konzerte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd090f animated-fast elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"2cd090f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a4123e animated-fast elementor-invisible elementor-widget elementor-widget-MEC\" data-id=\"5a4123e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"past-concerts\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"MEC.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mec-wrap mec-skin-list-container  \" id=\"mec_skin_1557\">\r\n\r\n    \r\n            <div class=\"mec-skin-list-events-container\" id=\"mec_skin_events_1557\">\r\n        <div class=\"mec-wrap \">\r\n\t<div class=\"mec-event-list-classic\">\r\n\t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202507-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4318\" href=\"https:\/\/kasparzehnder.com\/de\/events\/kirche-bremgarten-b-bern-ensemble-mit-vier-2025\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Freitag, 4th Juli 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4318\" href=\"https:\/\/kasparzehnder.com\/de\/events\/kirche-bremgarten-b-bern-ensemble-mit-vier-2025\/\" target=\"_blank\" rel=\"noopener\">Kirche Bremgarten b. Bern, Ensemble &#8222;mit vier&#8220;<\/a><\/h4>\r\n                                                                                                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202506-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4383\" href=\"https:\/\/kasparzehnder.com\/de\/events\/abendmusiken-im-berner-muenster\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Dienstag, 17th Juni 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4383\" href=\"https:\/\/kasparzehnder.com\/de\/events\/abendmusiken-im-berner-muenster\/\" target=\"_blank\" rel=\"noopener\">Abendmusiken im Berner M\u00fcnster<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Berner M\u00fcnster<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.abendmusiken.ch\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202506-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4317\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-reithalle\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Samstag, 14th Juni 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4317\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-reithalle\/\" target=\"_blank\" rel=\"noopener\">Der Peer Gynt z B\u00e4rn<\/a><\/h4>\r\n                                                                                <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.bko.ch\/de\/index.php\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202506-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4317\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-reithalle\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Freitag, 13th Juni 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4317\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-reithalle\/\" target=\"_blank\" rel=\"noopener\">Der Peer Gynt z B\u00e4rn<\/a><\/h4>\r\n                                                                                <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.bko.ch\/de\/index.php\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202505-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4314\" href=\"https:\/\/kasparzehnder.com\/de\/events\/antibes-fr-orchestre-national-de-cannes\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Samstag, 3rd Mai 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4314\" href=\"https:\/\/kasparzehnder.com\/de\/events\/antibes-fr-orchestre-national-de-cannes\/\" target=\"_blank\" rel=\"noopener\">Antibes (FR), Orchestre National de Cannes<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Auditorium du Conservatoire - Antibes<\/div><\/div>                                                                                                            <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202504-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4307\" href=\"https:\/\/kasparzehnder.com\/de\/events\/loches-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Samstag, 5th April 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4307\" href=\"https:\/\/kasparzehnder.com\/de\/events\/loches-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\">LOCHES (FR), Orchestre National des Pays de Loire<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Espace Agn\u00e8s Sorel<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/onpl.fr\/concert\/flute-et-harpe-mozart-a-lhonneur\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202504-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4306\" href=\"https:\/\/kasparzehnder.com\/de\/events\/nantes-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Freitag, 4th April 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4306\" href=\"https:\/\/kasparzehnder.com\/de\/events\/nantes-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\">Nantes (FR), Orchestre National des Pays de Loire<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> La Cit\u00e9 des Congr\u00e8s<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/onpl.fr\/concert\/flute-et-harpe-mozart-a-lhonneur\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202504-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4305\" href=\"https:\/\/kasparzehnder.com\/de\/events\/angers-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Donnerstag, 3rd April 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4305\" href=\"https:\/\/kasparzehnder.com\/de\/events\/angers-fr-orchestre-national-des-pays-de-loire\/\" target=\"_blank\" rel=\"noopener\">Angers (FR), Orchestre National des Pays de Loire<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Centre de Congr\u00e8s<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/onpl.fr\/concert\/flute-et-harpe-mozart-a-lhonneur\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202503-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4303\" href=\"https:\/\/kasparzehnder.com\/de\/events\/hradec-kralove-cz-s4-ihre-majestaet-die-fhk\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Sonntag, 30th M\u00e4rz 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4303\" href=\"https:\/\/kasparzehnder.com\/de\/events\/hradec-kralove-cz-s4-ihre-majestaet-die-fhk\/\" target=\"_blank\" rel=\"noopener\">Hradec Kr\u00e1lov\u00e9 (CZ), S4 \u2013 Ihre Majest\u00e4t die FHK<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> S\u00e1l Filharmonie Hradec Kr\u00e1lov\u00e9<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.fhk.cz\/calendar\/1256\/S4_Jeji_velicenstvo_FHK\/source-hpcalendar\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202503-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4374\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-ch-berner-kammerorchester-claire-huangci-klavier\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Freitag, 21st M\u00e4rz 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4374\" href=\"https:\/\/kasparzehnder.com\/de\/events\/bern-ch-berner-kammerorchester-claire-huangci-klavier\/\" target=\"_blank\" rel=\"noopener\">Bern (CH), Berner Kammerorchester, Claire Huangci (Klavier)<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Yehudi Menuhin Forum Bern<\/div><\/div>                                                                                                            <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202503-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4376\" href=\"https:\/\/kasparzehnder.com\/de\/events\/murten-ch-duo-kaspar-zehnder-floete-tatjana-fuog-klavier\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Samstag, 8th M\u00e4rz 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4376\" href=\"https:\/\/kasparzehnder.com\/de\/events\/murten-ch-duo-kaspar-zehnder-floete-tatjana-fuog-klavier\/\" target=\"_blank\" rel=\"noopener\">Murten (CH), Duo Kaspar Zehnder (Fl\u00f6te), Tatjana Fuog (Klavier)<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> Franz\u00f6sische Kirche Murten<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.kirche-murten.ch\/serenaden\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\r\n            \r\n                        <article class=\"mec-past-event mec-event-article  mec-clear  mec-divider-toggle mec-toggle-202503-1557\" itemscope>\r\n                                    <div class=\"mec-event-image\"><a class=\"mec-color-hover\" data-event-id=\"4302\" href=\"https:\/\/kasparzehnder.com\/de\/events\/hradec-kralove-cz-b6-spiegel-im-spiegel\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\r\n                                            <div class=\"mec-event-date mec-color\"><i class=\"mec-sl-calendar\"><\/i> <span class=\"mec-start-date-label\">Donnerstag, 6th M\u00e4rz 2025<\/span><\/div>\r\n                        <div class=\"mec-event-time mec-color\"><\/div>\r\n                                                                                <h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"4302\" href=\"https:\/\/kasparzehnder.com\/de\/events\/hradec-kralove-cz-b6-spiegel-im-spiegel\/\" target=\"_blank\" rel=\"noopener\">Hradec Kr\u00e1lov\u00e9 (CZ), B6 \u2013 Spiegel im Spiegel<\/a><\/h4>\r\n                    <div class=\"mec-event-detail\"><div class=\"mec-event-loc-place\"><i class=\"mec-sl-map-marker\"><\/i> S\u00e1l Filharmonie Hradec Kr\u00e1lov\u00e9<\/div><\/div>                                                            <a class=\"mec_grid_btn elementor-button-link elementor-button\" href=\"https:\/\/www.fhk.cz\/calendar\/1246\/B6_Zrcadlo_v_zrcadle\/source-hpcalendar\/\">Konzertinfo \/ Tickets<\/a>                                                <\/article>\r\n            \t\t\t<\/div>\r\n<\/div>\r\n\r\n    <\/div>\r\n    <div class=\"mec-skin-list-no-events-container mec-util-hidden\" id=\"mec_skin_no_events_1557\">\r\n        Keine Veranstaltung gefunden!    <\/div>\r\n    \r\n    \r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e684fd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e684fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Next events &#8211; Concerts Konzertkalender Mai 2025 16 Mai 2025 20:00 &#8211; 22:30 Paris (FR), Anton\u00edn Dvo\u0159\u00e1ks &#8222;Rusalka&#8220; Konzertinfo \/ Tickets: https:\/\/orchestredemassy.com\/touslesconcerts\/rusalka\/ Op\u00e9ra Massy, Paris Oper Konzertinfo \/ Tickets 18 Mai 2025 16:00 &#8211; 18:30 Paris (FR), Anton\u00edn Dvo\u0159\u00e1ks &#8222;Rusalka&#8220; Konzertinfo \/ Tickets: https:\/\/orchestredemassy.com\/touslesconcerts\/rusalka\/ Op\u00e9ra Massy, Paris Oper Konzertinfo \/ Tickets Juni 2025 13 Juni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-309","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/pages\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/comments?post=309"}],"version-history":[{"count":287,"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/pages\/309\/revisions"}],"predecessor-version":[{"id":4497,"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/pages\/309\/revisions\/4497"}],"wp:attachment":[{"href":"https:\/\/kasparzehnder.com\/de\/wp-json\/wp\/v2\/media?parent=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}